{"id":10394,"date":"2018-12-12T20:51:48","date_gmt":"2018-12-12T19:51:48","guid":{"rendered":"http:\/\/utrera.salesianos.edu\/colegio\/blog\/cuentacuentos\/"},"modified":"2018-12-12T20:51:53","modified_gmt":"2018-12-12T19:51:53","slug":"cuentacuentos","status":"publish","type":"post","link":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/cuentacuentos\/","title":{"rendered":"Cuentacuentos"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>[et_pb_section bb_built=\u00bb1&#8243; admin_label=\u00bbsection\u00bb custom_padding=\u00bb2px|0px|54px|0px\u00bb][et_pb_row admin_label=\u00bbrow\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb background_size=\u00bbinitial\u00bb][et_pb_column type=\u00bb4_4&#8243;][et_pb_text admin_label=\u00bbEntradilla\u00bb text_font=\u00bb|on|||\u00bb text_orientation=\u00bbjustified\u00bb use_border_color=\u00bboff\u00bb border_color=\u00bb#ffffff\u00bb border_style=\u00bbsolid\u00bb _builder_version=\u00bb3.17.2&#8243;]<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbDesarrollo\u00bb text_orientation=\u00bbjustified\u00bb use_border_color=\u00bboff\u00bb border_color=\u00bb#ffffff\u00bb border_style=\u00bbsolid\u00bb _builder_version=\u00bb3.17.2&#8243;]<\/p>\n<p>Esta semana, los alumnos de 1\u00baESO han visitado a sus compa\u00f1eros de Educaci\u00f3n Infantil, para compartir con ellos la experiencia del CUENTACUENTOS. Con esta actividad, donde los alumnos han creado y narrado sus propios cuentos, se busca fomentar el gusto por la lectura entre los alumnos de las distintas etapas; a trav\u00e9s de un momento de encuentro en el que han podido disfrutar juntos.<\/p>\n<div class=\"yj6qo\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-10395\" src=\"http:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/1-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/1-300x225.jpg 300w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/1-768x576.jpg 768w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/1.jpg 1024w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/1-510x382.jpg 510w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-10397\" src=\"http:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/2-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/2-300x225.jpg 300w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/2-768x576.jpg 768w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/2.jpg 1024w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/2-510x382.jpg 510w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-10399\" src=\"http:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/3-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/3-300x225.jpg 300w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/3-768x576.jpg 768w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/3.jpg 1024w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/3-510x382.jpg 510w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-10401\" src=\"http:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/4-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/4-300x169.jpg 300w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/4-768x432.jpg 768w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/4-1024x576.jpg 1024w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/4-1080x608.jpg 1080w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/4.jpg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-10403\" src=\"http:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/5-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/5-300x169.jpg 300w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/5-768x432.jpg 768w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/5-1024x576.jpg 1024w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/5-1080x608.jpg 1080w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/5.jpg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-10405\" src=\"http:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/6-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/6-300x225.jpg 300w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/6-768x576.jpg 768w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/6.jpg 1024w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/6-510x382.jpg 510w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-10407\" src=\"http:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/7-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/7-300x225.jpg 300w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/7-768x576.jpg 768w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/7.jpg 1024w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/7-510x382.jpg 510w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-10409\" src=\"http:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/8-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/8-225x300.jpg 225w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/8.jpg 768w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Esta semana, los alumnos de 1\u00baESO han visitado a sus compa\u00f1eros de Educaci\u00f3n Infantil, para compartir con ellos la experiencia del CUENTACUENTOS. Con esta actividad, donde los alumnos han creado y narrado sus propios cuentos, se busca fomentar el gusto por la lectura entre los alumnos de las distintas etapas; a trav\u00e9s de un [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":10399,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1,27,26],"tags":[],"class_list":["post-10394","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casa","category-colegio","category-portada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cuentacuentos - Colegio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/utrera.salesianos.edu\/colegio\/blog\/cuentacuentos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cuentacuentos - Colegio\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Esta semana, los alumnos de 1\u00baESO han visitado a sus compa\u00f1eros de Educaci\u00f3n Infantil, para compartir con ellos la experiencia del CUENTACUENTOS. Con esta actividad, donde los alumnos han creado y narrado sus propios cuentos, se busca fomentar el gusto por la lectura entre los alumnos de las distintas etapas; a trav\u00e9s de un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/utrera.salesianos.edu\/colegio\/blog\/cuentacuentos\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-12T19:51:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-12T19:51:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"gestorweb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"gestorweb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/cuentacuentos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/cuentacuentos\\\/\"},\"author\":{\"name\":\"gestorweb\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/ac8db01a976ac89189ba916e9686b5db\"},\"headline\":\"Cuentacuentos\",\"datePublished\":\"2018-12-12T19:51:48+00:00\",\"dateModified\":\"2018-12-12T19:51:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/cuentacuentos\\\/\"},\"wordCount\":163,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/cuentacuentos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/3.jpg\",\"articleSection\":[\"Casa\",\"Colegio\",\"Portada\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/cuentacuentos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/cuentacuentos\\\/\",\"url\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/cuentacuentos\\\/\",\"name\":\"Cuentacuentos - Colegio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/cuentacuentos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/cuentacuentos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/3.jpg\",\"datePublished\":\"2018-12-12T19:51:48+00:00\",\"dateModified\":\"2018-12-12T19:51:53+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/ac8db01a976ac89189ba916e9686b5db\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/cuentacuentos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/cuentacuentos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/cuentacuentos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/3.jpg\",\"contentUrl\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/3.jpg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/cuentacuentos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cuentacuentos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio\",\"description\":\"P\u00e1gina oficial Salesianos Utrera\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/ac8db01a976ac89189ba916e9686b5db\",\"name\":\"gestorweb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c028c8e3289342dd18d05321559f21f89ab10c3378522a3427307f228142899?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c028c8e3289342dd18d05321559f21f89ab10c3378522a3427307f228142899?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c028c8e3289342dd18d05321559f21f89ab10c3378522a3427307f228142899?s=96&d=mm&r=g\",\"caption\":\"gestorweb\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cuentacuentos - Colegio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/cuentacuentos\/","og_locale":"es_ES","og_type":"article","og_title":"Cuentacuentos - Colegio","og_description":"&nbsp; Esta semana, los alumnos de 1\u00baESO han visitado a sus compa\u00f1eros de Educaci\u00f3n Infantil, para compartir con ellos la experiencia del CUENTACUENTOS. Con esta actividad, donde los alumnos han creado y narrado sus propios cuentos, se busca fomentar el gusto por la lectura entre los alumnos de las distintas etapas; a trav\u00e9s de un [&hellip;]","og_url":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/cuentacuentos\/","og_site_name":"Colegio","article_published_time":"2018-12-12T19:51:48+00:00","article_modified_time":"2018-12-12T19:51:53+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/3.jpg","type":"image\/jpeg"}],"author":"gestorweb","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"gestorweb","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/cuentacuentos\/#article","isPartOf":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/cuentacuentos\/"},"author":{"name":"gestorweb","@id":"https:\/\/utrera.salesianos.edu\/colegio\/#\/schema\/person\/ac8db01a976ac89189ba916e9686b5db"},"headline":"Cuentacuentos","datePublished":"2018-12-12T19:51:48+00:00","dateModified":"2018-12-12T19:51:53+00:00","mainEntityOfPage":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/cuentacuentos\/"},"wordCount":163,"commentCount":0,"image":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/cuentacuentos\/#primaryimage"},"thumbnailUrl":"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/3.jpg","articleSection":["Casa","Colegio","Portada"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/utrera.salesianos.edu\/colegio\/blog\/cuentacuentos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/cuentacuentos\/","url":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/cuentacuentos\/","name":"Cuentacuentos - Colegio","isPartOf":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/cuentacuentos\/#primaryimage"},"image":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/cuentacuentos\/#primaryimage"},"thumbnailUrl":"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/3.jpg","datePublished":"2018-12-12T19:51:48+00:00","dateModified":"2018-12-12T19:51:53+00:00","author":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/#\/schema\/person\/ac8db01a976ac89189ba916e9686b5db"},"breadcrumb":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/cuentacuentos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/utrera.salesianos.edu\/colegio\/blog\/cuentacuentos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/cuentacuentos\/#primaryimage","url":"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/3.jpg","contentUrl":"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/3.jpg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/cuentacuentos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/utrera.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"Cuentacuentos"}]},{"@type":"WebSite","@id":"https:\/\/utrera.salesianos.edu\/colegio\/#website","url":"https:\/\/utrera.salesianos.edu\/colegio\/","name":"Colegio","description":"P\u00e1gina oficial Salesianos Utrera","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/utrera.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/utrera.salesianos.edu\/colegio\/#\/schema\/person\/ac8db01a976ac89189ba916e9686b5db","name":"gestorweb","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8c028c8e3289342dd18d05321559f21f89ab10c3378522a3427307f228142899?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8c028c8e3289342dd18d05321559f21f89ab10c3378522a3427307f228142899?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8c028c8e3289342dd18d05321559f21f89ab10c3378522a3427307f228142899?s=96&d=mm&r=g","caption":"gestorweb"}}]}},"_links":{"self":[{"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/10394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=10394"}],"version-history":[{"count":8,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/10394\/revisions"}],"predecessor-version":[{"id":10410,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/10394\/revisions\/10410"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media\/10399"}],"wp:attachment":[{"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=10394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/categories?post=10394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/tags?post=10394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}