{"id":10437,"date":"2018-12-14T11:15:34","date_gmt":"2018-12-14T10:15:34","guid":{"rendered":"http:\/\/utrera.salesianos.edu\/colegio\/blog\/2o-bachillerato-va-al-teatro\/"},"modified":"2018-12-14T11:15:36","modified_gmt":"2018-12-14T10:15:36","slug":"2o-bachillerato-va-al-teatro","status":"publish","type":"post","link":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/2o-bachillerato-va-al-teatro\/","title":{"rendered":"2\u00ba bachillerato va al teatro"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>[et_pb_section bb_built=\u00bb1&#8243; admin_label=\u00bbsection\u00bb custom_padding=\u00bb2px|0px|54px|0px\u00bb][et_pb_row admin_label=\u00bbrow\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb background_size=\u00bbinitial\u00bb][et_pb_column type=\u00bb4_4&#8243;][et_pb_text admin_label=\u00bbEntradilla\u00bb text_font=\u00bb|on|||\u00bb text_orientation=\u00bbjustified\u00bb use_border_color=\u00bboff\u00bb border_color=\u00bb#ffffff\u00bb border_style=\u00bbsolid\u00bb _builder_version=\u00bb3.18.6&#8243;]<\/p>\n<p><strong>Por D. Andr\u00e9s Barrios<\/strong><\/p>\n<p><em><b>Los alumnos de 2\u00ba de bachillerato participan en la obra de teatro \u00abhistoria de una escalera\u00bb<\/b><\/em><\/p>\n<hr \/>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbDesarrollo\u00bb text_orientation=\u00bbjustified\u00bb use_border_color=\u00bboff\u00bb border_color=\u00bb#ffffff\u00bb border_style=\u00bbsolid\u00bb _builder_version=\u00bb3.18.6&#8243;]<\/p>\n<p>Tras la Guerra Civil, la sociedad espa\u00f1ola vivi\u00f3 un dur\u00edsimo per\u00edodo de necesidades. Antonio Buero Vallejo fue un magn\u00edfico cronista de su tiempo y lo reflej\u00f3 con extraordinaria dureza en su obra <strong><em>Historia de una escalera<\/em><\/strong>, un retrato de vecindad de una escalera cualquiera de una ciudad cualquiera de Espa\u00f1a, donde conviven ilusiones y fracasos de unos personajes que bien pudieran ser los espectadores de aquellos a\u00f1os. Eso lo han vivido nuestros alumnos de 2\u00ba Bachillerato cuando han asistido a la representaci\u00f3n de la obra en el Teatro Quintero de Sevilla, una adaptaci\u00f3n muy acertada de la obra en la que, con s\u00f3lo cuatro actores, se ha sabido reflejar el sentido de la pieza teatral de Buero Vallejo.<\/p>\n<p>Antes del teatro, los alumnos han visitado el rectorado de la Universidad de Sevilla y la Iglesia del Salvador, donde han podido disfrutar de la magn\u00edfica restauraci\u00f3n llevada a cabo en 2008 y que la ha dejado reluciente y espl\u00e9ndida.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-10438\" src=\"http:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/1-2-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/1-2-300x169.jpg 300w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/1-2-768x432.jpg 768w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/1-2-1024x576.jpg 1024w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/1-2-1080x608.jpg 1080w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/1-2.jpg 1328w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-10440\" src=\"http:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/2-1-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/2-1-300x169.jpg 300w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/2-1-768x432.jpg 768w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/2-1-1024x576.jpg 1024w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/2-1-1080x608.jpg 1080w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/2-1.jpg 1328w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-10442\" src=\"http:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/6-1-300x199.jpg\" alt=\"\" width=\"300\" height=\"199\" srcset=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/6-1-300x199.jpg 300w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/6-1-768x509.jpg 768w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/6-1-1024x679.jpg 1024w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/6-1-1080x716.jpg 1080w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/6-1.jpg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por D. Andr\u00e9s BarriosLos alumnos de 2\u00ba de bachillerato participan en la obra de teatro \u00abhistoria de una escalera\u00bb Tras la Guerra Civil, la sociedad espa\u00f1ola vivi\u00f3 un dur\u00edsimo per\u00edodo de necesidades. Antonio Buero Vallejo fue un magn\u00edfico cronista de su tiempo y lo reflej\u00f3 con extraordinaria dureza en su obra Historia de una escalera, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":10442,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[27,26],"tags":[],"class_list":["post-10437","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colegio","category-portada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>2\u00ba bachillerato va al teatro - Colegio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/utrera.salesianos.edu\/colegio\/blog\/2o-bachillerato-va-al-teatro\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2\u00ba bachillerato va al teatro - Colegio\" \/>\n<meta property=\"og:description\" content=\"Por D. Andr\u00e9s BarriosLos alumnos de 2\u00ba de bachillerato participan en la obra de teatro &quot;historia de una escalera&quot; Tras la Guerra Civil, la sociedad espa\u00f1ola vivi\u00f3 un dur\u00edsimo per\u00edodo de necesidades. Antonio Buero Vallejo fue un magn\u00edfico cronista de su tiempo y lo reflej\u00f3 con extraordinaria dureza en su obra Historia de una escalera, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/utrera.salesianos.edu\/colegio\/blog\/2o-bachillerato-va-al-teatro\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-14T10:15:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-14T10:15:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/6-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1061\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"gestorweb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"gestorweb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/2o-bachillerato-va-al-teatro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/2o-bachillerato-va-al-teatro\\\/\"},\"author\":{\"name\":\"gestorweb\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/ac8db01a976ac89189ba916e9686b5db\"},\"headline\":\"2\u00ba bachillerato va al teatro\",\"datePublished\":\"2018-12-14T10:15:34+00:00\",\"dateModified\":\"2018-12-14T10:15:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/2o-bachillerato-va-al-teatro\\\/\"},\"wordCount\":286,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/2o-bachillerato-va-al-teatro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/6-1.jpg\",\"articleSection\":[\"Colegio\",\"Portada\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/2o-bachillerato-va-al-teatro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/2o-bachillerato-va-al-teatro\\\/\",\"url\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/2o-bachillerato-va-al-teatro\\\/\",\"name\":\"2\u00ba bachillerato va al teatro - Colegio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/2o-bachillerato-va-al-teatro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/2o-bachillerato-va-al-teatro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/6-1.jpg\",\"datePublished\":\"2018-12-14T10:15:34+00:00\",\"dateModified\":\"2018-12-14T10:15:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/ac8db01a976ac89189ba916e9686b5db\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/2o-bachillerato-va-al-teatro\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/2o-bachillerato-va-al-teatro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/2o-bachillerato-va-al-teatro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/6-1.jpg\",\"contentUrl\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/6-1.jpg\",\"width\":1600,\"height\":1061},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/2o-bachillerato-va-al-teatro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2\u00ba bachillerato va al teatro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio\",\"description\":\"P\u00e1gina oficial Salesianos Utrera\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/ac8db01a976ac89189ba916e9686b5db\",\"name\":\"gestorweb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c028c8e3289342dd18d05321559f21f89ab10c3378522a3427307f228142899?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c028c8e3289342dd18d05321559f21f89ab10c3378522a3427307f228142899?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c028c8e3289342dd18d05321559f21f89ab10c3378522a3427307f228142899?s=96&d=mm&r=g\",\"caption\":\"gestorweb\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2\u00ba bachillerato va al teatro - Colegio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/2o-bachillerato-va-al-teatro\/","og_locale":"es_ES","og_type":"article","og_title":"2\u00ba bachillerato va al teatro - Colegio","og_description":"Por D. Andr\u00e9s BarriosLos alumnos de 2\u00ba de bachillerato participan en la obra de teatro \"historia de una escalera\" Tras la Guerra Civil, la sociedad espa\u00f1ola vivi\u00f3 un dur\u00edsimo per\u00edodo de necesidades. Antonio Buero Vallejo fue un magn\u00edfico cronista de su tiempo y lo reflej\u00f3 con extraordinaria dureza en su obra Historia de una escalera, [&hellip;]","og_url":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/2o-bachillerato-va-al-teatro\/","og_site_name":"Colegio","article_published_time":"2018-12-14T10:15:34+00:00","article_modified_time":"2018-12-14T10:15:36+00:00","og_image":[{"width":1600,"height":1061,"url":"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/6-1.jpg","type":"image\/jpeg"}],"author":"gestorweb","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"gestorweb","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/2o-bachillerato-va-al-teatro\/#article","isPartOf":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/2o-bachillerato-va-al-teatro\/"},"author":{"name":"gestorweb","@id":"https:\/\/utrera.salesianos.edu\/colegio\/#\/schema\/person\/ac8db01a976ac89189ba916e9686b5db"},"headline":"2\u00ba bachillerato va al teatro","datePublished":"2018-12-14T10:15:34+00:00","dateModified":"2018-12-14T10:15:36+00:00","mainEntityOfPage":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/2o-bachillerato-va-al-teatro\/"},"wordCount":286,"commentCount":0,"image":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/2o-bachillerato-va-al-teatro\/#primaryimage"},"thumbnailUrl":"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/6-1.jpg","articleSection":["Colegio","Portada"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/utrera.salesianos.edu\/colegio\/blog\/2o-bachillerato-va-al-teatro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/2o-bachillerato-va-al-teatro\/","url":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/2o-bachillerato-va-al-teatro\/","name":"2\u00ba bachillerato va al teatro - Colegio","isPartOf":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/2o-bachillerato-va-al-teatro\/#primaryimage"},"image":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/2o-bachillerato-va-al-teatro\/#primaryimage"},"thumbnailUrl":"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/6-1.jpg","datePublished":"2018-12-14T10:15:34+00:00","dateModified":"2018-12-14T10:15:36+00:00","author":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/#\/schema\/person\/ac8db01a976ac89189ba916e9686b5db"},"breadcrumb":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/2o-bachillerato-va-al-teatro\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/utrera.salesianos.edu\/colegio\/blog\/2o-bachillerato-va-al-teatro\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/2o-bachillerato-va-al-teatro\/#primaryimage","url":"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/6-1.jpg","contentUrl":"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/6-1.jpg","width":1600,"height":1061},{"@type":"BreadcrumbList","@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/2o-bachillerato-va-al-teatro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/utrera.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"2\u00ba bachillerato va al teatro"}]},{"@type":"WebSite","@id":"https:\/\/utrera.salesianos.edu\/colegio\/#website","url":"https:\/\/utrera.salesianos.edu\/colegio\/","name":"Colegio","description":"P\u00e1gina oficial Salesianos Utrera","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/utrera.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/utrera.salesianos.edu\/colegio\/#\/schema\/person\/ac8db01a976ac89189ba916e9686b5db","name":"gestorweb","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8c028c8e3289342dd18d05321559f21f89ab10c3378522a3427307f228142899?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8c028c8e3289342dd18d05321559f21f89ab10c3378522a3427307f228142899?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8c028c8e3289342dd18d05321559f21f89ab10c3378522a3427307f228142899?s=96&d=mm&r=g","caption":"gestorweb"}}]}},"_links":{"self":[{"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/10437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=10437"}],"version-history":[{"count":3,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/10437\/revisions"}],"predecessor-version":[{"id":10443,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/10437\/revisions\/10443"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media\/10442"}],"wp:attachment":[{"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=10437"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/categories?post=10437"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/tags?post=10437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}