{"id":10448,"date":"2018-12-19T12:52:28","date_gmt":"2018-12-19T11:52:28","guid":{"rendered":"https:\/\/utrera.salesianos.edu\/colegio\/?p=10448"},"modified":"2018-12-20T13:22:50","modified_gmt":"2018-12-20T12:22:50","slug":"eso-fpb-y-bachillerato-de-excursion-en-diciembre","status":"publish","type":"post","link":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/eso-fpb-y-bachillerato-de-excursion-en-diciembre\/","title":{"rendered":"ESO, FPB y bachillerato de excursi\u00f3n en Diciembre."},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>[et_pb_section bb_built=\u00bb1&#8243; admin_label=\u00bbsection\u00bb custom_padding=\u00bb2px|0px|54px|0px\u00bb][et_pb_row admin_label=\u00bbrow\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb background_size=\u00bbinitial\u00bb][et_pb_column type=\u00bb4_4&#8243;][et_pb_text admin_label=\u00bbEntradilla\u00bb text_font=\u00bb|on|||\u00bb text_orientation=\u00bbjustified\u00bb use_border_color=\u00bboff\u00bb border_color=\u00bb#ffffff\u00bb border_style=\u00bbsolid\u00bb _builder_version=\u00bb3.18.7&#8243;]<\/p>\n<p>ESO, FPB y Bachillerato se moviliza en la \u00faltima semana del a\u00f1o en las distintas actividades complementarias organizadas por los seminarios y tutor\u00edas.<\/p>\n<hr \/>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbDesarrollo\u00bb text_orientation=\u00bbjustified\u00bb use_border_color=\u00bboff\u00bb border_color=\u00bb#ffffff\u00bb border_style=\u00bbsolid\u00bb _builder_version=\u00bb3.18.7&#8243;]<\/p>\n<p>Visitas a C\u00f3rdoba , Do\u00f1ana y C\u00e1diz, Senderismo a la Sierra de San Pablo en Montellano y participar en la obra de teatro \u201cHistoria de una escalera\u201d. Son las salidas en las que nuestros alumnos han compartido experiencias y han disfrutado de un d\u00eda entre compa\u00f1eros y amigos en la \u00faltima semana de diciembre.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-10449\" src=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/WhatsApp-Image-2018-12-13-at-17.44.21-300x199.jpeg\" alt=\"\" width=\"300\" height=\"199\" srcset=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/WhatsApp-Image-2018-12-13-at-17.44.21-300x199.jpeg 300w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/WhatsApp-Image-2018-12-13-at-17.44.21-768x509.jpeg 768w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/WhatsApp-Image-2018-12-13-at-17.44.21-1024x679.jpeg 1024w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/WhatsApp-Image-2018-12-13-at-17.44.21-1080x716.jpeg 1080w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/WhatsApp-Image-2018-12-13-at-17.44.21.jpeg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-10451\" src=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/WhatsApp-Image-2018-12-18-at-12.31.38-300x169.jpeg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/WhatsApp-Image-2018-12-18-at-12.31.38-300x169.jpeg 300w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/WhatsApp-Image-2018-12-18-at-12.31.38-768x432.jpeg 768w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/WhatsApp-Image-2018-12-18-at-12.31.38-1024x576.jpeg 1024w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/WhatsApp-Image-2018-12-18-at-12.31.38-1080x608.jpeg 1080w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/WhatsApp-Image-2018-12-18-at-12.31.38.jpeg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-10453\" src=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/WhatsApp-Image-2018-12-18-at-14.01.21-300x169.jpeg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/WhatsApp-Image-2018-12-18-at-14.01.21-300x169.jpeg 300w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/WhatsApp-Image-2018-12-18-at-14.01.21-768x432.jpeg 768w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/WhatsApp-Image-2018-12-18-at-14.01.21-1024x576.jpeg 1024w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/WhatsApp-Image-2018-12-18-at-14.01.21-1080x608.jpeg 1080w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/WhatsApp-Image-2018-12-18-at-14.01.21.jpeg 1328w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-10455\" src=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/WhatsApp-Image-2018-12-18-at-10.45.57-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/WhatsApp-Image-2018-12-18-at-10.45.57-300x225.jpeg 300w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/WhatsApp-Image-2018-12-18-at-10.45.57-768x576.jpeg 768w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/WhatsApp-Image-2018-12-18-at-10.45.57-1024x768.jpeg 1024w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/WhatsApp-Image-2018-12-18-at-10.45.57-510x382.jpeg 510w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/WhatsApp-Image-2018-12-18-at-10.45.57-1080x810.jpeg 1080w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/WhatsApp-Image-2018-12-18-at-10.45.57.jpeg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-10457\" src=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/WhatsApp-Image-2018-12-19-at-11.36.12-225x300.jpeg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/WhatsApp-Image-2018-12-19-at-11.36.12-225x300.jpeg 225w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/WhatsApp-Image-2018-12-19-at-11.36.12-768x1024.jpeg 768w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/WhatsApp-Image-2018-12-19-at-11.36.12-1080x1440.jpeg 1080w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/WhatsApp-Image-2018-12-19-at-11.36.12.jpeg 1200w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ESO, FPB y Bachillerato se moviliza en la \u00faltima semana del a\u00f1o en las distintas actividades complementarias organizadas por los seminarios y tutor\u00edas. Visitas a C\u00f3rdoba , Do\u00f1ana y C\u00e1diz, Senderismo a la Sierra de San Pablo en Montellano y participar en la obra de teatro \u201cHistoria de una escalera\u201d. Son las salidas en las [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":10449,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1,27,26],"tags":[],"class_list":["post-10448","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casa","category-colegio","category-portada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ESO, FPB y bachillerato de excursi\u00f3n en Diciembre. - Colegio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/utrera.salesianos.edu\/colegio\/blog\/eso-fpb-y-bachillerato-de-excursion-en-diciembre\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ESO, FPB y bachillerato de excursi\u00f3n en Diciembre. - Colegio\" \/>\n<meta property=\"og:description\" content=\"ESO, FPB y Bachillerato se moviliza en la \u00faltima semana del a\u00f1o en las distintas actividades complementarias organizadas por los seminarios y tutor\u00edas. Visitas a C\u00f3rdoba , Do\u00f1ana y C\u00e1diz, Senderismo a la Sierra de San Pablo en Montellano y participar en la obra de teatro \u201cHistoria de una escalera\u201d. Son las salidas en las [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/utrera.salesianos.edu\/colegio\/blog\/eso-fpb-y-bachillerato-de-excursion-en-diciembre\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-19T11:52:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-20T12:22:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/WhatsApp-Image-2018-12-13-at-17.44.21.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1061\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mariodomene\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mariodomene\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/eso-fpb-y-bachillerato-de-excursion-en-diciembre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/eso-fpb-y-bachillerato-de-excursion-en-diciembre\\\/\"},\"author\":{\"name\":\"mariodomene\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/dd02563cdf14aad19151b1f4e5a93317\"},\"headline\":\"ESO, FPB y bachillerato de excursi\u00f3n en Diciembre.\",\"datePublished\":\"2018-12-19T11:52:28+00:00\",\"dateModified\":\"2018-12-20T12:22:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/eso-fpb-y-bachillerato-de-excursion-en-diciembre\\\/\"},\"wordCount\":186,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/eso-fpb-y-bachillerato-de-excursion-en-diciembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/WhatsApp-Image-2018-12-13-at-17.44.21.jpeg\",\"articleSection\":[\"Casa\",\"Colegio\",\"Portada\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/eso-fpb-y-bachillerato-de-excursion-en-diciembre\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/eso-fpb-y-bachillerato-de-excursion-en-diciembre\\\/\",\"url\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/eso-fpb-y-bachillerato-de-excursion-en-diciembre\\\/\",\"name\":\"ESO, FPB y bachillerato de excursi\u00f3n en Diciembre. - Colegio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/eso-fpb-y-bachillerato-de-excursion-en-diciembre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/eso-fpb-y-bachillerato-de-excursion-en-diciembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/WhatsApp-Image-2018-12-13-at-17.44.21.jpeg\",\"datePublished\":\"2018-12-19T11:52:28+00:00\",\"dateModified\":\"2018-12-20T12:22:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/dd02563cdf14aad19151b1f4e5a93317\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/eso-fpb-y-bachillerato-de-excursion-en-diciembre\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/eso-fpb-y-bachillerato-de-excursion-en-diciembre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/eso-fpb-y-bachillerato-de-excursion-en-diciembre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/WhatsApp-Image-2018-12-13-at-17.44.21.jpeg\",\"contentUrl\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/WhatsApp-Image-2018-12-13-at-17.44.21.jpeg\",\"width\":1600,\"height\":1061},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/eso-fpb-y-bachillerato-de-excursion-en-diciembre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ESO, FPB y bachillerato de excursi\u00f3n en Diciembre.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio\",\"description\":\"P\u00e1gina oficial Salesianos Utrera\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/dd02563cdf14aad19151b1f4e5a93317\",\"name\":\"mariodomene\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/293b2342311027306384a82e2162f8e72d14d7fdaa772de80a25dd4858691697?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/293b2342311027306384a82e2162f8e72d14d7fdaa772de80a25dd4858691697?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/293b2342311027306384a82e2162f8e72d14d7fdaa772de80a25dd4858691697?s=96&d=mm&r=g\",\"caption\":\"mariodomene\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ESO, FPB y bachillerato de excursi\u00f3n en Diciembre. - Colegio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/eso-fpb-y-bachillerato-de-excursion-en-diciembre\/","og_locale":"es_ES","og_type":"article","og_title":"ESO, FPB y bachillerato de excursi\u00f3n en Diciembre. - Colegio","og_description":"ESO, FPB y Bachillerato se moviliza en la \u00faltima semana del a\u00f1o en las distintas actividades complementarias organizadas por los seminarios y tutor\u00edas. Visitas a C\u00f3rdoba , Do\u00f1ana y C\u00e1diz, Senderismo a la Sierra de San Pablo en Montellano y participar en la obra de teatro \u201cHistoria de una escalera\u201d. Son las salidas en las [&hellip;]","og_url":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/eso-fpb-y-bachillerato-de-excursion-en-diciembre\/","og_site_name":"Colegio","article_published_time":"2018-12-19T11:52:28+00:00","article_modified_time":"2018-12-20T12:22:50+00:00","og_image":[{"width":1600,"height":1061,"url":"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/WhatsApp-Image-2018-12-13-at-17.44.21.jpeg","type":"image\/jpeg"}],"author":"mariodomene","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mariodomene","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/eso-fpb-y-bachillerato-de-excursion-en-diciembre\/#article","isPartOf":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/eso-fpb-y-bachillerato-de-excursion-en-diciembre\/"},"author":{"name":"mariodomene","@id":"https:\/\/utrera.salesianos.edu\/colegio\/#\/schema\/person\/dd02563cdf14aad19151b1f4e5a93317"},"headline":"ESO, FPB y bachillerato de excursi\u00f3n en Diciembre.","datePublished":"2018-12-19T11:52:28+00:00","dateModified":"2018-12-20T12:22:50+00:00","mainEntityOfPage":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/eso-fpb-y-bachillerato-de-excursion-en-diciembre\/"},"wordCount":186,"commentCount":0,"image":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/eso-fpb-y-bachillerato-de-excursion-en-diciembre\/#primaryimage"},"thumbnailUrl":"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/WhatsApp-Image-2018-12-13-at-17.44.21.jpeg","articleSection":["Casa","Colegio","Portada"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/utrera.salesianos.edu\/colegio\/blog\/eso-fpb-y-bachillerato-de-excursion-en-diciembre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/eso-fpb-y-bachillerato-de-excursion-en-diciembre\/","url":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/eso-fpb-y-bachillerato-de-excursion-en-diciembre\/","name":"ESO, FPB y bachillerato de excursi\u00f3n en Diciembre. - Colegio","isPartOf":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/eso-fpb-y-bachillerato-de-excursion-en-diciembre\/#primaryimage"},"image":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/eso-fpb-y-bachillerato-de-excursion-en-diciembre\/#primaryimage"},"thumbnailUrl":"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/WhatsApp-Image-2018-12-13-at-17.44.21.jpeg","datePublished":"2018-12-19T11:52:28+00:00","dateModified":"2018-12-20T12:22:50+00:00","author":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/#\/schema\/person\/dd02563cdf14aad19151b1f4e5a93317"},"breadcrumb":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/eso-fpb-y-bachillerato-de-excursion-en-diciembre\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/utrera.salesianos.edu\/colegio\/blog\/eso-fpb-y-bachillerato-de-excursion-en-diciembre\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/eso-fpb-y-bachillerato-de-excursion-en-diciembre\/#primaryimage","url":"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/WhatsApp-Image-2018-12-13-at-17.44.21.jpeg","contentUrl":"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/12\/WhatsApp-Image-2018-12-13-at-17.44.21.jpeg","width":1600,"height":1061},{"@type":"BreadcrumbList","@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/eso-fpb-y-bachillerato-de-excursion-en-diciembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/utrera.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"ESO, FPB y bachillerato de excursi\u00f3n en Diciembre."}]},{"@type":"WebSite","@id":"https:\/\/utrera.salesianos.edu\/colegio\/#website","url":"https:\/\/utrera.salesianos.edu\/colegio\/","name":"Colegio","description":"P\u00e1gina oficial Salesianos Utrera","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/utrera.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/utrera.salesianos.edu\/colegio\/#\/schema\/person\/dd02563cdf14aad19151b1f4e5a93317","name":"mariodomene","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/293b2342311027306384a82e2162f8e72d14d7fdaa772de80a25dd4858691697?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/293b2342311027306384a82e2162f8e72d14d7fdaa772de80a25dd4858691697?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/293b2342311027306384a82e2162f8e72d14d7fdaa772de80a25dd4858691697?s=96&d=mm&r=g","caption":"mariodomene"}}]}},"_links":{"self":[{"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/10448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=10448"}],"version-history":[{"count":17,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/10448\/revisions"}],"predecessor-version":[{"id":10482,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/10448\/revisions\/10482"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media\/10449"}],"wp:attachment":[{"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=10448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/categories?post=10448"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/tags?post=10448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}