{"id":12631,"date":"2021-10-25T09:32:55","date_gmt":"2021-10-25T07:32:55","guid":{"rendered":"https:\/\/utrera.salesianos.edu\/colegio\/?p=12631"},"modified":"2021-10-25T09:33:00","modified_gmt":"2021-10-25T07:33:00","slug":"nuevo-proyecto-de-exploracion-de-la-estratosfera-realizado-por-alumnos-de-bachillerato","status":"publish","type":"post","link":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/nuevo-proyecto-de-exploracion-de-la-estratosfera-realizado-por-alumnos-de-bachillerato\/","title":{"rendered":"NUEVO PROYECTO DE EXPLORACI\u00d3N DE LA ESTRATOSFERA REALIZADO POR ALUMNOS DE BACHILLERATO"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbsection\u00bb _builder_version=\u00bb3.22&#8243; custom_padding=\u00bb2px|0px|54px|0px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row admin_label=\u00bbrow\u00bb _builder_version=\u00bb3.25&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb3.25&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text admin_label=\u00bbEntradilla\u00bb _builder_version=\u00bb4.10.8&#8243; text_font=\u00bb|on|||\u00bb text_orientation=\u00bbjustified\u00bb hover_enabled=\u00bb0&#8243; use_border_color=\u00bboff\u00bb border_color=\u00bb#ffffff\u00bb border_style=\u00bbsolid\u00bb global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p>Ya ha tenido lugar la Presentaci\u00f3n del Proyecto de Exploraci\u00f3n de la Estratosfera mediante el lanzamiento de un globo a los alumnos de ciencias de 1\u00ba de bachillerato.<\/p>\n<hr \/>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbDesarrollo\u00bb _builder_version=\u00bb4.10.8&#8243; text_orientation=\u00bbjustified\u00bb hover_enabled=\u00bb0&#8243; use_border_color=\u00bboff\u00bb border_color=\u00bb#ffffff\u00bb border_style=\u00bbsolid\u00bb global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12632 alignnone size-medium\" src=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2021\/10\/IMG-20211023-WA0018-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12634 alignnone size-medium\" src=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2021\/10\/IMG-20211023-WA0019-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12636 alignnone size-medium\" src=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2021\/10\/IMG-20211023-WA0021-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" \/> <a href=\"https:\/\/utrera.salesianos.edu\/wp-content\/uploads\/2021\/10\/Plantilla-actualizada-vertical.docx\" rel=\"attachment wp-att-62251\">Plantilla actualizada vertical<\/a>Alejandro Jos Gallego, ingeniero con amplia experiencia en el lanzamiento de globos, present\u00f3 el proyecto mostrando a los alumnos en qu\u00e9 consiste, las principales cuestiones a las que tendr\u00e1n que enfrentarse, e im\u00e1genes y v\u00eddeos de lanzamientos anteriores. Agradecemos enormemente su colaboraci\u00f3n.<\/p>\n<p>\u00a0A lo largo del proyecto, los alumnos aprender\u00e1n los conceptos y principios cient\u00edficos necesarios, investigar\u00e1n y realizar\u00e1n experimentos a trav\u00e9s de una serie de retos que los guiar\u00e1n en el dise\u00f1o, hasta culminar el proyecto con el lanzamiento.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ya ha tenido lugar la Presentaci\u00f3n del Proyecto de Exploraci\u00f3n de la Estratosfera mediante el lanzamiento de un globo a los alumnos de ciencias de 1\u00ba de bachillerato. Plantilla actualizada verticalAlejandro Jos Gallego, ingeniero con amplia experiencia en el lanzamiento de globos, present\u00f3 el proyecto mostrando a los alumnos en qu\u00e9 consiste, las principales cuestiones [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":12634,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1,27,26],"tags":[],"class_list":["post-12631","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casa","category-colegio","category-portada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NUEVO PROYECTO DE EXPLORACI\u00d3N DE LA ESTRATOSFERA REALIZADO POR ALUMNOS DE BACHILLERATO - Colegio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/utrera.salesianos.edu\/colegio\/blog\/nuevo-proyecto-de-exploracion-de-la-estratosfera-realizado-por-alumnos-de-bachillerato\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NUEVO PROYECTO DE EXPLORACI\u00d3N DE LA ESTRATOSFERA REALIZADO POR ALUMNOS DE BACHILLERATO - Colegio\" \/>\n<meta property=\"og:description\" content=\"Ya ha tenido lugar la Presentaci\u00f3n del Proyecto de Exploraci\u00f3n de la Estratosfera mediante el lanzamiento de un globo a los alumnos de ciencias de 1\u00ba de bachillerato. Plantilla actualizada verticalAlejandro Jos Gallego, ingeniero con amplia experiencia en el lanzamiento de globos, present\u00f3 el proyecto mostrando a los alumnos en qu\u00e9 consiste, las principales cuestiones [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/utrera.salesianos.edu\/colegio\/blog\/nuevo-proyecto-de-exploracion-de-la-estratosfera-realizado-por-alumnos-de-bachillerato\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-25T07:32:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-25T07:33:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2021\/10\/IMG-20211023-WA0019.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mariodomene\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mariodomene\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/nuevo-proyecto-de-exploracion-de-la-estratosfera-realizado-por-alumnos-de-bachillerato\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/nuevo-proyecto-de-exploracion-de-la-estratosfera-realizado-por-alumnos-de-bachillerato\\\/\"},\"author\":{\"name\":\"mariodomene\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/dd02563cdf14aad19151b1f4e5a93317\"},\"headline\":\"NUEVO PROYECTO DE EXPLORACI\u00d3N DE LA ESTRATOSFERA REALIZADO POR ALUMNOS DE BACHILLERATO\",\"datePublished\":\"2021-10-25T07:32:55+00:00\",\"dateModified\":\"2021-10-25T07:33:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/nuevo-proyecto-de-exploracion-de-la-estratosfera-realizado-por-alumnos-de-bachillerato\\\/\"},\"wordCount\":263,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/nuevo-proyecto-de-exploracion-de-la-estratosfera-realizado-por-alumnos-de-bachillerato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/IMG-20211023-WA0019.jpg\",\"articleSection\":[\"Casa\",\"Colegio\",\"Portada\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/nuevo-proyecto-de-exploracion-de-la-estratosfera-realizado-por-alumnos-de-bachillerato\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/nuevo-proyecto-de-exploracion-de-la-estratosfera-realizado-por-alumnos-de-bachillerato\\\/\",\"url\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/nuevo-proyecto-de-exploracion-de-la-estratosfera-realizado-por-alumnos-de-bachillerato\\\/\",\"name\":\"NUEVO PROYECTO DE EXPLORACI\u00d3N DE LA ESTRATOSFERA REALIZADO POR ALUMNOS DE BACHILLERATO - Colegio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/nuevo-proyecto-de-exploracion-de-la-estratosfera-realizado-por-alumnos-de-bachillerato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/nuevo-proyecto-de-exploracion-de-la-estratosfera-realizado-por-alumnos-de-bachillerato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/IMG-20211023-WA0019.jpg\",\"datePublished\":\"2021-10-25T07:32:55+00:00\",\"dateModified\":\"2021-10-25T07:33:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/dd02563cdf14aad19151b1f4e5a93317\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/nuevo-proyecto-de-exploracion-de-la-estratosfera-realizado-por-alumnos-de-bachillerato\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/nuevo-proyecto-de-exploracion-de-la-estratosfera-realizado-por-alumnos-de-bachillerato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/nuevo-proyecto-de-exploracion-de-la-estratosfera-realizado-por-alumnos-de-bachillerato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/IMG-20211023-WA0019.jpg\",\"contentUrl\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/IMG-20211023-WA0019.jpg\",\"width\":1600,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/nuevo-proyecto-de-exploracion-de-la-estratosfera-realizado-por-alumnos-de-bachillerato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NUEVO PROYECTO DE EXPLORACI\u00d3N DE LA ESTRATOSFERA REALIZADO POR ALUMNOS DE BACHILLERATO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio\",\"description\":\"P\u00e1gina oficial Salesianos Utrera\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/dd02563cdf14aad19151b1f4e5a93317\",\"name\":\"mariodomene\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/293b2342311027306384a82e2162f8e72d14d7fdaa772de80a25dd4858691697?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/293b2342311027306384a82e2162f8e72d14d7fdaa772de80a25dd4858691697?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/293b2342311027306384a82e2162f8e72d14d7fdaa772de80a25dd4858691697?s=96&d=mm&r=g\",\"caption\":\"mariodomene\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NUEVO PROYECTO DE EXPLORACI\u00d3N DE LA ESTRATOSFERA REALIZADO POR ALUMNOS DE BACHILLERATO - Colegio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/nuevo-proyecto-de-exploracion-de-la-estratosfera-realizado-por-alumnos-de-bachillerato\/","og_locale":"es_ES","og_type":"article","og_title":"NUEVO PROYECTO DE EXPLORACI\u00d3N DE LA ESTRATOSFERA REALIZADO POR ALUMNOS DE BACHILLERATO - Colegio","og_description":"Ya ha tenido lugar la Presentaci\u00f3n del Proyecto de Exploraci\u00f3n de la Estratosfera mediante el lanzamiento de un globo a los alumnos de ciencias de 1\u00ba de bachillerato. Plantilla actualizada verticalAlejandro Jos Gallego, ingeniero con amplia experiencia en el lanzamiento de globos, present\u00f3 el proyecto mostrando a los alumnos en qu\u00e9 consiste, las principales cuestiones [&hellip;]","og_url":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/nuevo-proyecto-de-exploracion-de-la-estratosfera-realizado-por-alumnos-de-bachillerato\/","og_site_name":"Colegio","article_published_time":"2021-10-25T07:32:55+00:00","article_modified_time":"2021-10-25T07:33:00+00:00","og_image":[{"width":1600,"height":1600,"url":"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2021\/10\/IMG-20211023-WA0019.jpg","type":"image\/jpeg"}],"author":"mariodomene","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mariodomene","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/nuevo-proyecto-de-exploracion-de-la-estratosfera-realizado-por-alumnos-de-bachillerato\/#article","isPartOf":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/nuevo-proyecto-de-exploracion-de-la-estratosfera-realizado-por-alumnos-de-bachillerato\/"},"author":{"name":"mariodomene","@id":"https:\/\/utrera.salesianos.edu\/colegio\/#\/schema\/person\/dd02563cdf14aad19151b1f4e5a93317"},"headline":"NUEVO PROYECTO DE EXPLORACI\u00d3N DE LA ESTRATOSFERA REALIZADO POR ALUMNOS DE BACHILLERATO","datePublished":"2021-10-25T07:32:55+00:00","dateModified":"2021-10-25T07:33:00+00:00","mainEntityOfPage":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/nuevo-proyecto-de-exploracion-de-la-estratosfera-realizado-por-alumnos-de-bachillerato\/"},"wordCount":263,"commentCount":0,"image":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/nuevo-proyecto-de-exploracion-de-la-estratosfera-realizado-por-alumnos-de-bachillerato\/#primaryimage"},"thumbnailUrl":"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2021\/10\/IMG-20211023-WA0019.jpg","articleSection":["Casa","Colegio","Portada"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/utrera.salesianos.edu\/colegio\/blog\/nuevo-proyecto-de-exploracion-de-la-estratosfera-realizado-por-alumnos-de-bachillerato\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/nuevo-proyecto-de-exploracion-de-la-estratosfera-realizado-por-alumnos-de-bachillerato\/","url":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/nuevo-proyecto-de-exploracion-de-la-estratosfera-realizado-por-alumnos-de-bachillerato\/","name":"NUEVO PROYECTO DE EXPLORACI\u00d3N DE LA ESTRATOSFERA REALIZADO POR ALUMNOS DE BACHILLERATO - Colegio","isPartOf":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/nuevo-proyecto-de-exploracion-de-la-estratosfera-realizado-por-alumnos-de-bachillerato\/#primaryimage"},"image":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/nuevo-proyecto-de-exploracion-de-la-estratosfera-realizado-por-alumnos-de-bachillerato\/#primaryimage"},"thumbnailUrl":"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2021\/10\/IMG-20211023-WA0019.jpg","datePublished":"2021-10-25T07:32:55+00:00","dateModified":"2021-10-25T07:33:00+00:00","author":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/#\/schema\/person\/dd02563cdf14aad19151b1f4e5a93317"},"breadcrumb":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/nuevo-proyecto-de-exploracion-de-la-estratosfera-realizado-por-alumnos-de-bachillerato\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/utrera.salesianos.edu\/colegio\/blog\/nuevo-proyecto-de-exploracion-de-la-estratosfera-realizado-por-alumnos-de-bachillerato\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/nuevo-proyecto-de-exploracion-de-la-estratosfera-realizado-por-alumnos-de-bachillerato\/#primaryimage","url":"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2021\/10\/IMG-20211023-WA0019.jpg","contentUrl":"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2021\/10\/IMG-20211023-WA0019.jpg","width":1600,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/nuevo-proyecto-de-exploracion-de-la-estratosfera-realizado-por-alumnos-de-bachillerato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/utrera.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"NUEVO PROYECTO DE EXPLORACI\u00d3N DE LA ESTRATOSFERA REALIZADO POR ALUMNOS DE BACHILLERATO"}]},{"@type":"WebSite","@id":"https:\/\/utrera.salesianos.edu\/colegio\/#website","url":"https:\/\/utrera.salesianos.edu\/colegio\/","name":"Colegio","description":"P\u00e1gina oficial Salesianos Utrera","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/utrera.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/utrera.salesianos.edu\/colegio\/#\/schema\/person\/dd02563cdf14aad19151b1f4e5a93317","name":"mariodomene","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/293b2342311027306384a82e2162f8e72d14d7fdaa772de80a25dd4858691697?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/293b2342311027306384a82e2162f8e72d14d7fdaa772de80a25dd4858691697?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/293b2342311027306384a82e2162f8e72d14d7fdaa772de80a25dd4858691697?s=96&d=mm&r=g","caption":"mariodomene"}}]}},"_links":{"self":[{"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/12631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=12631"}],"version-history":[{"count":7,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/12631\/revisions"}],"predecessor-version":[{"id":12641,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/12631\/revisions\/12641"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media\/12634"}],"wp:attachment":[{"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=12631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/categories?post=12631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/tags?post=12631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}