{"id":14422,"date":"2023-01-09T08:39:21","date_gmt":"2023-01-09T07:39:21","guid":{"rendered":"https:\/\/utrera.salesianos.edu\/colegio\/?p=14422"},"modified":"2023-01-09T08:39:28","modified_gmt":"2023-01-09T07:39:28","slug":"d-juan-manuel-espinosa-salesiano-coadjutor-fallece-a-los-87-anos-tras-tres-decadas-en-utrera","status":"publish","type":"post","link":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/d-juan-manuel-espinosa-salesiano-coadjutor-fallece-a-los-87-anos-tras-tres-decadas-en-utrera\/","title":{"rendered":"D. Juan Manuel Espinosa, salesiano coadjutor fallece a los 87 a\u00f1os, tras tres d\u00e9cadas en Utrera."},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbsection\u00bb _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb2px|0px|54px|0px\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row admin_label=\u00bbrow\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text admin_label=\u00bbEntradilla\u00bb _builder_version=\u00bb4.17.3&#8243; text_font=\u00bb|on|||\u00bb text_orientation=\u00bbjustified\u00bb hover_enabled=\u00bb0&#8243; use_border_color=\u00bboff\u00bb border_color=\u00bb#ffffff\u00bb border_style=\u00bbsolid\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p style=\"background: white;margin: 0cm 0cm 7.5pt 0cm\"><span style=\"font-size: 10.5pt;font-family: 'Helvetica',sans-serif;color: #363636\">Este sevillano, del barrio de Triana, lleg\u00f3 a Utrera hace tres d\u00e9cadas. Desde entonces se ha convertido en uno de los miembros de la comunidad religiosa m\u00e1s conocidos. Ejerci\u00f3 como profesor, escribi\u00f3 varios libros y compuso numerosos cantos, himnos, villancicos y marchas.<\/span><\/p>\n<hr \/>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbDesarrollo\u00bb _builder_version=\u00bb4.17.3&#8243; text_orientation=\u00bbjustified\u00bb hover_enabled=\u00bb0&#8243; use_border_color=\u00bboff\u00bb border_color=\u00bb#ffffff\u00bb border_style=\u00bbsolid\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p>Pero si por alguna faceta ser\u00e1 especialmente recordado es por la de m\u00fasico, habiendo sido uno de los principales pilares musicales de la Casa salesiana de la ciudad a lo largo de estos a\u00f1os. Siempre junto a su inseparable \u00f3rgano, ha participado en infinidad de eventos y actos de la familia salesiana, entre los que se encuentran el pasado preg\u00f3n de Navidad.<\/p>\n<p>Se le recordar\u00e1 como fundador y director del coro Auxilium hace m\u00e1s de veinticinco a\u00f1os, participando en multitud de conciertos, funciones y distintos eventos.<\/p>\n<p>En el Cielo ya no faltar\u00e1 la m\u00fasica y el buen humor. Descanse en Paz.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-14423 alignnone size-medium\" src=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/01\/1673248851085-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/01\/1673248851085-300x300.jpg 300w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/01\/1673248851085-150x150.jpg 150w, https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/01\/1673248851085.jpg 467w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"wp-image-14425 alignnone size-medium\" src=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/01\/1673248851093-300x191.jpg\" alt=\"\" width=\"300\" height=\"191\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"wp-image-14427 alignnone size-medium\" src=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/01\/1673248851099-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"wp-image-14429 alignnone size-medium\" src=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/01\/1673248851107-300x226.jpg\" alt=\"\" width=\"300\" height=\"226\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"wp-image-14431 alignnone size-medium\" src=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/01\/1673248851114-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" \/> <a href=\"https:\/\/utrera.salesianos.edu\/wp-content\/uploads\/2023\/01\/blanco.docx\" rel=\"attachment wp-att-63493\">blanco<\/a><\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbT\u00edtulo Galer\u00eda\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<blockquote>\n<h3><strong>Galer\u00eda de fotos:<\/strong><\/h3>\n<\/blockquote>\n<p>[\/et_pb_text][et_pb_gallery gallery_ids=\u00bb14266,14265,14264,14263&#8243; posts_number=\u00bb8&#8243; show_title_and_caption=\u00bboff\u00bb zoom_icon_color=\u00bb#d12525&#8243; _builder_version=\u00bb4.16&#8243; use_border_color=\u00bboff\u00bb border_color=\u00bb#ffffff\u00bb border_style=\u00bbsolid\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este sevillano, del barrio de Triana, lleg\u00f3 a Utrera hace tres d\u00e9cadas. Desde entonces se ha convertido en uno de los miembros de la comunidad religiosa m\u00e1s conocidos. Ejerci\u00f3 como profesor, escribi\u00f3 varios libros y compuso numerosos cantos, himnos, villancicos y marchas. Pero si por alguna faceta ser\u00e1 especialmente recordado es por la de m\u00fasico, [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":14423,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1,27,26],"tags":[],"class_list":["post-14422","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casa","category-colegio","category-portada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D. Juan Manuel Espinosa, salesiano coadjutor fallece a los 87 a\u00f1os, tras tres d\u00e9cadas en Utrera. - Colegio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/utrera.salesianos.edu\/colegio\/blog\/d-juan-manuel-espinosa-salesiano-coadjutor-fallece-a-los-87-anos-tras-tres-decadas-en-utrera\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D. Juan Manuel Espinosa, salesiano coadjutor fallece a los 87 a\u00f1os, tras tres d\u00e9cadas en Utrera. - Colegio\" \/>\n<meta property=\"og:description\" content=\"Este sevillano, del barrio de Triana, lleg\u00f3 a Utrera hace tres d\u00e9cadas. Desde entonces se ha convertido en uno de los miembros de la comunidad religiosa m\u00e1s conocidos. Ejerci\u00f3 como profesor, escribi\u00f3 varios libros y compuso numerosos cantos, himnos, villancicos y marchas. Pero si por alguna faceta ser\u00e1 especialmente recordado es por la de m\u00fasico, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/utrera.salesianos.edu\/colegio\/blog\/d-juan-manuel-espinosa-salesiano-coadjutor-fallece-a-los-87-anos-tras-tres-decadas-en-utrera\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-09T07:39:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-09T07:39:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/01\/1673248851085.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"467\" \/>\n\t<meta property=\"og:image:height\" content=\"467\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mariodomene\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mariodomene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/d-juan-manuel-espinosa-salesiano-coadjutor-fallece-a-los-87-anos-tras-tres-decadas-en-utrera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/d-juan-manuel-espinosa-salesiano-coadjutor-fallece-a-los-87-anos-tras-tres-decadas-en-utrera\\\/\"},\"author\":{\"name\":\"mariodomene\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/dd02563cdf14aad19151b1f4e5a93317\"},\"headline\":\"D. Juan Manuel Espinosa, salesiano coadjutor fallece a los 87 a\u00f1os, tras tres d\u00e9cadas en Utrera.\",\"datePublished\":\"2023-01-09T07:39:21+00:00\",\"dateModified\":\"2023-01-09T07:39:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/d-juan-manuel-espinosa-salesiano-coadjutor-fallece-a-los-87-anos-tras-tres-decadas-en-utrera\\\/\"},\"wordCount\":387,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/d-juan-manuel-espinosa-salesiano-coadjutor-fallece-a-los-87-anos-tras-tres-decadas-en-utrera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/01\\\/1673248851085.jpg\",\"articleSection\":[\"Casa\",\"Colegio\",\"Portada\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/d-juan-manuel-espinosa-salesiano-coadjutor-fallece-a-los-87-anos-tras-tres-decadas-en-utrera\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/d-juan-manuel-espinosa-salesiano-coadjutor-fallece-a-los-87-anos-tras-tres-decadas-en-utrera\\\/\",\"url\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/d-juan-manuel-espinosa-salesiano-coadjutor-fallece-a-los-87-anos-tras-tres-decadas-en-utrera\\\/\",\"name\":\"D. Juan Manuel Espinosa, salesiano coadjutor fallece a los 87 a\u00f1os, tras tres d\u00e9cadas en Utrera. - Colegio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/d-juan-manuel-espinosa-salesiano-coadjutor-fallece-a-los-87-anos-tras-tres-decadas-en-utrera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/d-juan-manuel-espinosa-salesiano-coadjutor-fallece-a-los-87-anos-tras-tres-decadas-en-utrera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/01\\\/1673248851085.jpg\",\"datePublished\":\"2023-01-09T07:39:21+00:00\",\"dateModified\":\"2023-01-09T07:39:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/dd02563cdf14aad19151b1f4e5a93317\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/d-juan-manuel-espinosa-salesiano-coadjutor-fallece-a-los-87-anos-tras-tres-decadas-en-utrera\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/d-juan-manuel-espinosa-salesiano-coadjutor-fallece-a-los-87-anos-tras-tres-decadas-en-utrera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/d-juan-manuel-espinosa-salesiano-coadjutor-fallece-a-los-87-anos-tras-tres-decadas-en-utrera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/01\\\/1673248851085.jpg\",\"contentUrl\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/01\\\/1673248851085.jpg\",\"width\":467,\"height\":467},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/d-juan-manuel-espinosa-salesiano-coadjutor-fallece-a-los-87-anos-tras-tres-decadas-en-utrera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D. Juan Manuel Espinosa, salesiano coadjutor fallece a los 87 a\u00f1os, tras tres d\u00e9cadas en Utrera.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio\",\"description\":\"P\u00e1gina oficial Salesianos Utrera\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/dd02563cdf14aad19151b1f4e5a93317\",\"name\":\"mariodomene\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/293b2342311027306384a82e2162f8e72d14d7fdaa772de80a25dd4858691697?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/293b2342311027306384a82e2162f8e72d14d7fdaa772de80a25dd4858691697?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/293b2342311027306384a82e2162f8e72d14d7fdaa772de80a25dd4858691697?s=96&d=mm&r=g\",\"caption\":\"mariodomene\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D. Juan Manuel Espinosa, salesiano coadjutor fallece a los 87 a\u00f1os, tras tres d\u00e9cadas en Utrera. - Colegio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/d-juan-manuel-espinosa-salesiano-coadjutor-fallece-a-los-87-anos-tras-tres-decadas-en-utrera\/","og_locale":"es_ES","og_type":"article","og_title":"D. Juan Manuel Espinosa, salesiano coadjutor fallece a los 87 a\u00f1os, tras tres d\u00e9cadas en Utrera. - Colegio","og_description":"Este sevillano, del barrio de Triana, lleg\u00f3 a Utrera hace tres d\u00e9cadas. Desde entonces se ha convertido en uno de los miembros de la comunidad religiosa m\u00e1s conocidos. Ejerci\u00f3 como profesor, escribi\u00f3 varios libros y compuso numerosos cantos, himnos, villancicos y marchas. Pero si por alguna faceta ser\u00e1 especialmente recordado es por la de m\u00fasico, [&hellip;]","og_url":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/d-juan-manuel-espinosa-salesiano-coadjutor-fallece-a-los-87-anos-tras-tres-decadas-en-utrera\/","og_site_name":"Colegio","article_published_time":"2023-01-09T07:39:21+00:00","article_modified_time":"2023-01-09T07:39:28+00:00","og_image":[{"width":467,"height":467,"url":"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/01\/1673248851085.jpg","type":"image\/jpeg"}],"author":"mariodomene","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mariodomene"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/d-juan-manuel-espinosa-salesiano-coadjutor-fallece-a-los-87-anos-tras-tres-decadas-en-utrera\/#article","isPartOf":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/d-juan-manuel-espinosa-salesiano-coadjutor-fallece-a-los-87-anos-tras-tres-decadas-en-utrera\/"},"author":{"name":"mariodomene","@id":"https:\/\/utrera.salesianos.edu\/colegio\/#\/schema\/person\/dd02563cdf14aad19151b1f4e5a93317"},"headline":"D. Juan Manuel Espinosa, salesiano coadjutor fallece a los 87 a\u00f1os, tras tres d\u00e9cadas en Utrera.","datePublished":"2023-01-09T07:39:21+00:00","dateModified":"2023-01-09T07:39:28+00:00","mainEntityOfPage":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/d-juan-manuel-espinosa-salesiano-coadjutor-fallece-a-los-87-anos-tras-tres-decadas-en-utrera\/"},"wordCount":387,"commentCount":0,"image":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/d-juan-manuel-espinosa-salesiano-coadjutor-fallece-a-los-87-anos-tras-tres-decadas-en-utrera\/#primaryimage"},"thumbnailUrl":"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/01\/1673248851085.jpg","articleSection":["Casa","Colegio","Portada"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/utrera.salesianos.edu\/colegio\/blog\/d-juan-manuel-espinosa-salesiano-coadjutor-fallece-a-los-87-anos-tras-tres-decadas-en-utrera\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/d-juan-manuel-espinosa-salesiano-coadjutor-fallece-a-los-87-anos-tras-tres-decadas-en-utrera\/","url":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/d-juan-manuel-espinosa-salesiano-coadjutor-fallece-a-los-87-anos-tras-tres-decadas-en-utrera\/","name":"D. Juan Manuel Espinosa, salesiano coadjutor fallece a los 87 a\u00f1os, tras tres d\u00e9cadas en Utrera. - Colegio","isPartOf":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/d-juan-manuel-espinosa-salesiano-coadjutor-fallece-a-los-87-anos-tras-tres-decadas-en-utrera\/#primaryimage"},"image":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/d-juan-manuel-espinosa-salesiano-coadjutor-fallece-a-los-87-anos-tras-tres-decadas-en-utrera\/#primaryimage"},"thumbnailUrl":"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/01\/1673248851085.jpg","datePublished":"2023-01-09T07:39:21+00:00","dateModified":"2023-01-09T07:39:28+00:00","author":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/#\/schema\/person\/dd02563cdf14aad19151b1f4e5a93317"},"breadcrumb":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/d-juan-manuel-espinosa-salesiano-coadjutor-fallece-a-los-87-anos-tras-tres-decadas-en-utrera\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/utrera.salesianos.edu\/colegio\/blog\/d-juan-manuel-espinosa-salesiano-coadjutor-fallece-a-los-87-anos-tras-tres-decadas-en-utrera\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/d-juan-manuel-espinosa-salesiano-coadjutor-fallece-a-los-87-anos-tras-tres-decadas-en-utrera\/#primaryimage","url":"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/01\/1673248851085.jpg","contentUrl":"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/01\/1673248851085.jpg","width":467,"height":467},{"@type":"BreadcrumbList","@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/d-juan-manuel-espinosa-salesiano-coadjutor-fallece-a-los-87-anos-tras-tres-decadas-en-utrera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/utrera.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"D. Juan Manuel Espinosa, salesiano coadjutor fallece a los 87 a\u00f1os, tras tres d\u00e9cadas en Utrera."}]},{"@type":"WebSite","@id":"https:\/\/utrera.salesianos.edu\/colegio\/#website","url":"https:\/\/utrera.salesianos.edu\/colegio\/","name":"Colegio","description":"P\u00e1gina oficial Salesianos Utrera","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/utrera.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/utrera.salesianos.edu\/colegio\/#\/schema\/person\/dd02563cdf14aad19151b1f4e5a93317","name":"mariodomene","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/293b2342311027306384a82e2162f8e72d14d7fdaa772de80a25dd4858691697?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/293b2342311027306384a82e2162f8e72d14d7fdaa772de80a25dd4858691697?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/293b2342311027306384a82e2162f8e72d14d7fdaa772de80a25dd4858691697?s=96&d=mm&r=g","caption":"mariodomene"}}]}},"_links":{"self":[{"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/14422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=14422"}],"version-history":[{"count":11,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/14422\/revisions"}],"predecessor-version":[{"id":14438,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/14422\/revisions\/14438"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media\/14423"}],"wp:attachment":[{"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=14422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/categories?post=14422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/tags?post=14422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}