{"id":14969,"date":"2023-04-26T08:37:16","date_gmt":"2023-04-26T06:37:16","guid":{"rendered":"https:\/\/utrera.salesianos.edu\/colegio\/?p=14969"},"modified":"2023-04-26T08:37:28","modified_gmt":"2023-04-26T06:37:28","slug":"dia-del-libro-2023","status":"publish","type":"post","link":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/dia-del-libro-2023\/","title":{"rendered":"D\u00cdA DEL LIBRO 2023"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbsection\u00bb _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb2px|0px|54px|0px\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row admin_label=\u00bbrow\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text admin_label=\u00bbEntradilla\u00bb _builder_version=\u00bb4.20.2&#8243; text_font=\u00bb|on|||\u00bb text_orientation=\u00bbjustified\u00bb hover_enabled=\u00bb0&#8243; use_border_color=\u00bboff\u00bb border_color=\u00bb#ffffff\u00bb border_style=\u00bbsolid\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p>El viernes 21 de Abril celebramos en nuestra Casa\u00a0 el D\u00eda del Libro.<\/p>\n<hr \/>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbDesarrollo\u00bb _builder_version=\u00bb4.20.2&#8243; text_orientation=\u00bbjustified\u00bb hover_enabled=\u00bb0&#8243; use_border_color=\u00bboff\u00bb border_color=\u00bb#ffffff\u00bb border_style=\u00bbsolid\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p>Para ello, ha colaborado con nosotros la escritora utrerana Montse Arisp\u00f3n, impartiendo una charla sobre su obra y el proceso de escritura a los alumnos de ESO y Bachillerato. Adem\u00e1s, se han realizado unas exposiciones sobre los beneficios de la lectura para los alumnos de Primero de ESO. Y, como no pod\u00eda faltar, este a\u00f1o nos hemos disfrazado de personajes hist\u00f3ricos. \u00a1Feliz D\u00eda del Libro 2023!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-14970 alignnone size-medium\" src=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/04\/1681915927372-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"wp-image-14972 alignnone size-medium\" src=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/04\/1682070773114-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"wp-image-14974 alignnone size-medium\" src=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/04\/1682070773120-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"wp-image-14976 alignnone size-medium\" src=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/04\/1682070773127-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"wp-image-14978 alignnone size-medium\" src=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/04\/1682070773140-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"wp-image-14980 alignnone size-medium\" src=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/04\/1682070773148-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"wp-image-14982 alignnone size-medium\" src=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/04\/1682070886956-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"wp-image-14984 alignnone size-medium\" src=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/04\/1682070886965-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"wp-image-14986 alignnone size-medium\" src=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/04\/1682070886971-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"wp-image-14988 alignnone size-medium\" src=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/04\/1682070886978-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"wp-image-14990 alignnone size-medium\" src=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/04\/1682070886985-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/> <a href=\"https:\/\/utrera.salesianos.edu\/wp-content\/uploads\/2023\/04\/blanco-2.docx\" rel=\"attachment wp-att-63869\">blanco<\/a><\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbT\u00edtulo Galer\u00eda\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<blockquote>\n<h3><strong>Galer\u00eda de fotos:<\/strong><\/h3>\n<\/blockquote>\n<p>[\/et_pb_text][et_pb_gallery gallery_ids=\u00bb14266,14265,14264,14263&#8243; posts_number=\u00bb8&#8243; show_title_and_caption=\u00bboff\u00bb zoom_icon_color=\u00bb#d12525&#8243; _builder_version=\u00bb4.16&#8243; use_border_color=\u00bboff\u00bb border_color=\u00bb#ffffff\u00bb border_style=\u00bbsolid\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El viernes 21 de Abril celebramos en nuestra Casa\u00a0 el D\u00eda del Libro. Para ello, ha colaborado con nosotros la escritora utrerana Montse Arisp\u00f3n, impartiendo una charla sobre su obra y el proceso de escritura a los alumnos de ESO y Bachillerato. Adem\u00e1s, se han realizado unas exposiciones sobre los beneficios de la lectura para [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":14974,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1,27,26],"tags":[],"class_list":["post-14969","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casa","category-colegio","category-portada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00cdA DEL LIBRO 2023 - Colegio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/utrera.salesianos.edu\/colegio\/blog\/dia-del-libro-2023\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00cdA DEL LIBRO 2023 - Colegio\" \/>\n<meta property=\"og:description\" content=\"El viernes 21 de Abril celebramos en nuestra Casa\u00a0 el D\u00eda del Libro. Para ello, ha colaborado con nosotros la escritora utrerana Montse Arisp\u00f3n, impartiendo una charla sobre su obra y el proceso de escritura a los alumnos de ESO y Bachillerato. Adem\u00e1s, se han realizado unas exposiciones sobre los beneficios de la lectura para [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/utrera.salesianos.edu\/colegio\/blog\/dia-del-libro-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-26T06:37:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-26T06:37:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/04\/1682070773120.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mariodomene\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mariodomene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/dia-del-libro-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/dia-del-libro-2023\\\/\"},\"author\":{\"name\":\"mariodomene\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/dd02563cdf14aad19151b1f4e5a93317\"},\"headline\":\"D\u00cdA DEL LIBRO 2023\",\"datePublished\":\"2023-04-26T06:37:16+00:00\",\"dateModified\":\"2023-04-26T06:37:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/dia-del-libro-2023\\\/\"},\"wordCount\":307,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/dia-del-libro-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/04\\\/1682070773120.jpg\",\"articleSection\":[\"Casa\",\"Colegio\",\"Portada\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/dia-del-libro-2023\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/dia-del-libro-2023\\\/\",\"url\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/dia-del-libro-2023\\\/\",\"name\":\"D\u00cdA DEL LIBRO 2023 - Colegio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/dia-del-libro-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/dia-del-libro-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/04\\\/1682070773120.jpg\",\"datePublished\":\"2023-04-26T06:37:16+00:00\",\"dateModified\":\"2023-04-26T06:37:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/dd02563cdf14aad19151b1f4e5a93317\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/dia-del-libro-2023\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/dia-del-libro-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/dia-del-libro-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/04\\\/1682070773120.jpg\",\"contentUrl\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/04\\\/1682070773120.jpg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/blog\\\/dia-del-libro-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00cdA DEL LIBRO 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio\",\"description\":\"P\u00e1gina oficial Salesianos Utrera\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/dd02563cdf14aad19151b1f4e5a93317\",\"name\":\"mariodomene\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/293b2342311027306384a82e2162f8e72d14d7fdaa772de80a25dd4858691697?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/293b2342311027306384a82e2162f8e72d14d7fdaa772de80a25dd4858691697?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/293b2342311027306384a82e2162f8e72d14d7fdaa772de80a25dd4858691697?s=96&d=mm&r=g\",\"caption\":\"mariodomene\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00cdA DEL LIBRO 2023 - Colegio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/dia-del-libro-2023\/","og_locale":"es_ES","og_type":"article","og_title":"D\u00cdA DEL LIBRO 2023 - Colegio","og_description":"El viernes 21 de Abril celebramos en nuestra Casa\u00a0 el D\u00eda del Libro. Para ello, ha colaborado con nosotros la escritora utrerana Montse Arisp\u00f3n, impartiendo una charla sobre su obra y el proceso de escritura a los alumnos de ESO y Bachillerato. Adem\u00e1s, se han realizado unas exposiciones sobre los beneficios de la lectura para [&hellip;]","og_url":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/dia-del-libro-2023\/","og_site_name":"Colegio","article_published_time":"2023-04-26T06:37:16+00:00","article_modified_time":"2023-04-26T06:37:28+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/04\/1682070773120.jpg","type":"image\/jpeg"}],"author":"mariodomene","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mariodomene"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/dia-del-libro-2023\/#article","isPartOf":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/dia-del-libro-2023\/"},"author":{"name":"mariodomene","@id":"https:\/\/utrera.salesianos.edu\/colegio\/#\/schema\/person\/dd02563cdf14aad19151b1f4e5a93317"},"headline":"D\u00cdA DEL LIBRO 2023","datePublished":"2023-04-26T06:37:16+00:00","dateModified":"2023-04-26T06:37:28+00:00","mainEntityOfPage":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/dia-del-libro-2023\/"},"wordCount":307,"commentCount":0,"image":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/dia-del-libro-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/04\/1682070773120.jpg","articleSection":["Casa","Colegio","Portada"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/utrera.salesianos.edu\/colegio\/blog\/dia-del-libro-2023\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/dia-del-libro-2023\/","url":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/dia-del-libro-2023\/","name":"D\u00cdA DEL LIBRO 2023 - Colegio","isPartOf":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/dia-del-libro-2023\/#primaryimage"},"image":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/dia-del-libro-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/04\/1682070773120.jpg","datePublished":"2023-04-26T06:37:16+00:00","dateModified":"2023-04-26T06:37:28+00:00","author":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/#\/schema\/person\/dd02563cdf14aad19151b1f4e5a93317"},"breadcrumb":{"@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/dia-del-libro-2023\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/utrera.salesianos.edu\/colegio\/blog\/dia-del-libro-2023\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/dia-del-libro-2023\/#primaryimage","url":"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/04\/1682070773120.jpg","contentUrl":"https:\/\/utrera.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/04\/1682070773120.jpg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/utrera.salesianos.edu\/colegio\/blog\/dia-del-libro-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/utrera.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"D\u00cdA DEL LIBRO 2023"}]},{"@type":"WebSite","@id":"https:\/\/utrera.salesianos.edu\/colegio\/#website","url":"https:\/\/utrera.salesianos.edu\/colegio\/","name":"Colegio","description":"P\u00e1gina oficial Salesianos Utrera","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/utrera.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/utrera.salesianos.edu\/colegio\/#\/schema\/person\/dd02563cdf14aad19151b1f4e5a93317","name":"mariodomene","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/293b2342311027306384a82e2162f8e72d14d7fdaa772de80a25dd4858691697?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/293b2342311027306384a82e2162f8e72d14d7fdaa772de80a25dd4858691697?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/293b2342311027306384a82e2162f8e72d14d7fdaa772de80a25dd4858691697?s=96&d=mm&r=g","caption":"mariodomene"}}]}},"_links":{"self":[{"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/14969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=14969"}],"version-history":[{"count":23,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/14969\/revisions"}],"predecessor-version":[{"id":15003,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/14969\/revisions\/15003"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media\/14974"}],"wp:attachment":[{"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=14969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/categories?post=14969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/utrera.salesianos.edu\/colegio\/wp-json\/wp\/v2\/tags?post=14969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}