{"id":9894,"date":"2018-10-10T13:54:34","date_gmt":"2018-10-10T11:54:34","guid":{"rendered":"http:\/\/utrera.salesianos.edu\/jovenesendificultad\/?p=9894"},"modified":"2018-12-17T12:10:13","modified_gmt":"2018-12-17T11:10:13","slug":"el-nuevo-curso-viene-novedades-tics","status":"publish","type":"post","link":"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/blog\/el-nuevo-curso-viene-novedades-tics\/","title":{"rendered":"El nuevo curso viene con novedades TICs"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>Desde Oberti no podemos mantenernos al margen de los cambios a nivel econ\u00f3mico, social y tecnol\u00f3gico que se est\u00e1n produciendo en la sociedad actual. Es necesario adaptarse a las caracter\u00edsticas individuales y a las necesidades propias de nuestros destinatarios\/as, entre ellas el uso de las TIC en la educaci\u00f3n. De este modo podemos aportar mayor flexibilizaci\u00f3n en las trayectorias acad\u00e9micas y facilitar al m\u00e1ximo el desarrollo de sus potencialidades.<\/p>\n<p>En este comienzo de curso hemos querido apostar por la instalaci\u00f3n de un total de 5 Ordenadores, repartidos en las diferentes salas donde realizamos nuestro trabajo con los menores y sus familias, para suplir la necesidades propias del uso de las TICs en los centros educativos, ya que la mayor\u00eda\u00a0no poseen tales equipamientos en sus hogares.<\/p>\n<p>Adem\u00e1s contamos con conexi\u00f3n a internet de todos los equipos de la casa gracias a la colaboraci\u00f3n de una empresa utrerana de Internet\u00a0 <a href=\"http:\/\/www.wi-com.es\">WI-COM<\/a>. Agradecemos desde estas lineas a las personas y empresas que han colaborado en la instalaci\u00f3n de los equipos inform\u00e1ticos.<\/p>\n<style id=\"bwg-style-0\">    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails {      width: 1254px;              justify-content: center;        margin:0 auto !important;              background-color: rgba(255, 255, 255, 0.00);            padding-left: 4px;      padding-top: 4px;      max-width: 100%;            }        #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item {    justify-content: flex-start;      max-width: 250px;          }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item a {       margin-right: 4px;       margin-bottom: 4px;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item0 {      padding: 0px;            background-color:rgba(255,255,255, 0.30);      border: 0px none #CCCCCC;      opacity: 1.00;      border-radius: 0;      box-shadow: ;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 img {      max-height: none;      max-width: none;      padding: 0 !important;    }         @media only screen and (min-width: 480px) {\t\t#bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 img {\t\t\t-webkit-transition: all .3s; transition: all .3s;\t\t}\t\t#bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 img:hover {\t\t\t-ms-transform: scale(1.08);\t\t\t-webkit-transform: scale(1.08);\t\t\ttransform: scale(1.08);\t\t}\t\t      }\t    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 {      padding-top: 56%;    }        #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-title2,    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-ecommerce2 {      color: #CCCCCC;      font-family: Ubuntu;      font-size: 16px;      font-weight: bold;      padding: 2px;      text-shadow: 0px 0px 0px #888888;      max-height: 100%;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-thumb-description span {    color: #323A45;    font-family: Ubuntu;    font-size: 12px;    max-height: 100%;    word-wrap: break-word;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-play-icon2 {      font-size: 32px;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-ecommerce2 {      font-size: 19.2px;      color: #CCCCCC;    }    <\/style>    <div id=\"bwg_container1_0\"         class=\"bwg_container bwg_thumbnail bwg_thumbnails \"         data-right-click-protection=\"0\"         data-bwg=\"0\"         data-scroll=\"0\"         data-gallery-type=\"thumbnails\"         data-gallery-view-type=\"thumbnails\"         data-current-url=\"\/jovenesendificultad\/wp-json\/wp\/v2\/posts\/9894\"         data-lightbox-url=\"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/wp-admin\/admin-ajax.php?action=GalleryBox&#038;current_view=0&#038;gallery_id=4&#038;tag=0&#038;theme_id=1&#038;shortcode_id=11&#038;sort_by=order&#038;order_by=asc&#038;current_url=%2Fjovenesendificultad%2Fwp-json%2Fwp%2Fv2%2Fposts%2F9894\"         data-gallery-id=\"4\"         data-popup-width=\"800\"         data-popup-height=\"500\"         data-is-album=\"gallery\"         data-buttons-position=\"bottom\">      <div id=\"bwg_container2_0\">             <div id=\"ajax_loading_0\" class=\"bwg_loading_div_1\">      <div class=\"bwg_loading_div_2\">        <div class=\"bwg_loading_div_3\">          <div id=\"loading_div_0\" class=\"bwg_spider_ajax_loading\">          <\/div>        <\/div>      <\/div>    <\/div>            <form id=\"gal_front_form_0\"              class=\"bwg-hidden\"              method=\"post\"              action=\"#\"              data-current=\"0\"              data-shortcode-id=\"11\"              data-gallery-type=\"thumbnails\"              data-gallery-id=\"4\"              data-tag=\"0\"              data-album-id=\"0\"              data-theme-id=\"1\"              data-ajax-url=\"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/wp-admin\/admin-ajax.php?action=bwg_frontend_data\">          <div id=\"bwg_container3_0\" class=\"bwg-background bwg-background-0\">                <div data-max-count=\"5\"         data-thumbnail-width=\"250\"         data-bwg=\"0\"         data-gallery-id=\"4\"         data-lightbox-url=\"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/wp-admin\/admin-ajax.php?action=GalleryBox&amp;current_view=0&amp;gallery_id=4&amp;tag=0&amp;theme_id=1&amp;shortcode_id=11&amp;sort_by=order&amp;order_by=asc&amp;current_url=%2Fjovenesendificultad%2Fwp-json%2Fwp%2Fv2%2Fposts%2F9894\"         id=\"bwg_thumbnails_0\"         class=\"bwg-container-0 bwg-thumbnails bwg-standard-thumbnails bwg-container bwg-border-box\">            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"21\" href=\"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/wp-content\/uploads\/sites\/5\/photo-gallery\/20181009_180234.jpg?bwg=1539171461\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"21\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/wp-content\/uploads\/sites\/5\/photo-gallery\/thumb\/20181009_180234.jpg?bwg=1539171461\"                   src=\"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/wp-content\/uploads\/sites\/5\/photo-gallery\/thumb\/20181009_180234.jpg?bwg=1539171461\"                   alt=\"20181009 180234\"                   title=\"20181009 180234\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"20\" href=\"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/wp-content\/uploads\/sites\/5\/photo-gallery\/20181009_175915.jpg?bwg=1539171461\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"20\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/wp-content\/uploads\/sites\/5\/photo-gallery\/thumb\/20181009_175915.jpg?bwg=1539171461\"                   src=\"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/wp-content\/uploads\/sites\/5\/photo-gallery\/thumb\/20181009_175915.jpg?bwg=1539171461\"                   alt=\"20181009 175915\"                   title=\"20181009 175915\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"19\" href=\"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/wp-content\/uploads\/sites\/5\/photo-gallery\/20181009_180206.jpg?bwg=1539171461\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"19\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/wp-content\/uploads\/sites\/5\/photo-gallery\/thumb\/20181009_180206.jpg?bwg=1539171461\"                   src=\"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/wp-content\/uploads\/sites\/5\/photo-gallery\/thumb\/20181009_180206.jpg?bwg=1539171461\"                   alt=\"20181009 180206\"                   title=\"20181009 180206\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"18\" href=\"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/wp-content\/uploads\/sites\/5\/photo-gallery\/20181009_180018.jpg?bwg=1539171461\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"18\"                   data-width=\"\"                   data-height=\"\"                   data-src=\"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/wp-content\/uploads\/sites\/5\/photo-gallery\/thumb\/20181009_180018.jpg?bwg=1539171461\"                   src=\"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/wp-content\/uploads\/sites\/5\/photo-gallery\/thumb\/20181009_180018.jpg?bwg=1539171461\"                   alt=\"20181009 180018\"                   title=\"20181009 180018\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>          <\/div>    <style>      \/*pagination styles*\/      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 {\t\t\t\ttext-align: center;\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: segoe ui;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\tmargin: 6px 0 4px;\t\t\t\tdisplay: block;      }      @media only screen and (max-width : 320px) {      #bwg_container1_0 #bwg_container2_0 .displaying-num_0 {     \t display: none;      }      }      #bwg_container1_0 #bwg_container2_0 .displaying-num_0 {\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: segoe ui;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\tmargin-right: 10px;\t\t\t\tvertical-align: middle;      }      #bwg_container1_0 #bwg_container2_0 .paging-input_0 {\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: segoe ui;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\tvertical-align: middle;      }      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a.disabled,      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a.disabled:hover,      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a.disabled:focus,\t\t\t#bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 input.bwg_current_page {\t\t\t\tcursor: default;\t\t\t\tcolor: rgba(102, 102, 102, 0.5);      }      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a,      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 input.bwg_current_page {\t\t\t\tcursor: pointer;\t\t\t\ttext-align: center;\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: segoe ui;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\ttext-decoration: none;\t\t\t\tpadding: 3px 6px;\t\t\t\tmargin: 0;\t\t\t\tborder-radius: 0;\t\t\t\tborder-style: solid;\t\t\t\tborder-width: 1px;\t\t\t\tborder-color: #E3E3E3;\t\t\t\t\t\t\t\tbackground-color: rgba(255, 255, 255, 1.00);\t\t\t\tbox-shadow: 0;\t\t\t\ttransition: all 0.3s ease 0s;-webkit-transition: all 0.3s ease 0s;      }      <\/style>      <span class=\"bwg_nav_cont_0\">              <div class=\"tablenav-pages_0\">                  <\/div>                <input type=\"hidden\" id=\"page_number_0\" name=\"page_number_0\" value=\"1\" \/>      <script type=\"text\/javascript\">        if( jQuery('.bwg_nav_cont_0').length > 1 ) {          jQuery('.bwg_nav_cont_0').first().remove()        }        function spider_page_0(cur, x, y, load_more) {          if (typeof load_more == \"undefined\") {            var load_more = false;          }          if (jQuery(cur).hasClass('disabled')) {            return false;          }          var items_county_0 = 1;          switch (y) {            case 1:              if (x >= items_county_0) {                document.getElementById('page_number_0').value = items_county_0;              }              else {                document.getElementById('page_number_0').value = x + 1;              }              break;            case 2:              document.getElementById('page_number_0').value = items_county_0;              break;            case -1:              if (x == 1) {                document.getElementById('page_number_0').value = 1;              }              else {                document.getElementById('page_number_0').value = x - 1;              }              break;            case -2:              document.getElementById('page_number_0').value = 1;              break;\t\t\t\t\t\tcase 0:              document.getElementById('page_number_0').value = x;              break;            default:              document.getElementById('page_number_0').value = 1;          }          bwg_ajax('gal_front_form_0', '0', 'bwg_thumbnails_0', '0', '', 'gallery', 0, '', '', load_more, '', 1);        }                    jQuery('.first-page-0').on('click', function () {              spider_page_0(this, 1, -2, 'numeric');              return false;            });            jQuery('.prev-page-0').on('click', function () {              spider_page_0(this, 1, -1, 'numeric');              return false;            });            jQuery('.next-page-0').on('click', function () {              spider_page_0(this, 1, 1, 'numeric');              return false;            });            jQuery('.last-page-0').on('click', function () {              spider_page_0(this, 1, 2, 'numeric');              return false;            });        \t\t\t\t\/* Change page on input enter. *\/        function bwg_change_page_0( e, that ) {          if (  e.key == 'Enter' ) {            var to_page = parseInt(jQuery(that).val());            var pages_count = jQuery(that).parents(\".pagination-links\").data(\"pages-count\");            var current_url_param = jQuery(that).attr('data-url-info');            if (to_page > pages_count) {              to_page = 1;            }\t \t\t\t\t\t\t\t\t\t\t\t\tspider_page_0(this, to_page, 0, 'numeric');\t\t\t\t\t\t\treturn false;\t\t\t\t\t\t          }          return true;        }        jQuery('.bwg_load_btn_0').on('click', function () {            spider_page_0(this, 1, 1, true);            return false;        });      <\/script>      <\/span>                <\/div>        <\/form>        <style>          #bwg_container1_0 #bwg_container2_0 #spider_popup_overlay_0 {          background-color: #EEEEEE;          opacity: 0.60;          }          <\/style>        <div id=\"bwg_spider_popup_loading_0\" class=\"bwg_spider_popup_loading\"><\/div>        <div id=\"spider_popup_overlay_0\" class=\"spider_popup_overlay\" onclick=\"spider_destroypopup(1000)\"><\/div>        <input type=\"hidden\" id=\"bwg_random_seed_0\" value=\"1021696408\">                <\/div>    <\/div>    <script>      if (document.readyState === 'complete') {        if( typeof bwg_main_ready == 'function' ) {          if ( jQuery(\"#bwg_container1_0\").height() ) {            bwg_main_ready(jQuery(\"#bwg_container1_0\"));          }        }      } else {        document.addEventListener('DOMContentLoaded', function() {          if( typeof bwg_main_ready == 'function' ) {            if ( jQuery(\"#bwg_container1_0\").height() ) {             bwg_main_ready(jQuery(\"#bwg_container1_0\"));            }          }        });      }    <\/script>    \n","protected":false},"excerpt":{"rendered":"<p>Desde Oberti no podemos mantenernos al margen de los cambios a nivel econ\u00f3mico, social y tecnol\u00f3gico que se est\u00e1n produciendo en la sociedad actual. Es necesario adaptarse a las caracter\u00edsticas individuales y a las necesidades propias de nuestros destinatarios\/as, entre ellas el uso de las TIC en la educaci\u00f3n. De este modo podemos aportar mayor [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":9926,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[10],"tags":[],"class_list":["post-9894","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-portada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El nuevo curso viene con novedades TICs - Proyecto Oberti<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/blog\/el-nuevo-curso-viene-novedades-tics\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El nuevo curso viene con novedades TICs - Proyecto Oberti\" \/>\n<meta property=\"og:description\" content=\"Desde Oberti no podemos mantenernos al margen de los cambios a nivel econ\u00f3mico, social y tecnol\u00f3gico que se est\u00e1n produciendo en la sociedad actual. Es necesario adaptarse a las caracter\u00edsticas individuales y a las necesidades propias de nuestros destinatarios\/as, entre ellas el uso de las TIC en la educaci\u00f3n. De este modo podemos aportar mayor [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/blog\/el-nuevo-curso-viene-novedades-tics\/\" \/>\n<meta property=\"og:site_name\" content=\"Proyecto Oberti\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-10T11:54:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-17T11:10:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/wp-content\/uploads\/sites\/5\/2018\/10\/20181009_175915-1024x576.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"proyectooberti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"proyectooberti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/jovenesendificultad\\\/blog\\\/el-nuevo-curso-viene-novedades-tics\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/jovenesendificultad\\\/blog\\\/el-nuevo-curso-viene-novedades-tics\\\/\"},\"author\":{\"name\":\"proyectooberti\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/jovenesendificultad\\\/#\\\/schema\\\/person\\\/43f51a01b2adf8fbe0c47356fb20a543\"},\"headline\":\"El nuevo curso viene con novedades TICs\",\"datePublished\":\"2018-10-10T11:54:34+00:00\",\"dateModified\":\"2018-12-17T11:10:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/jovenesendificultad\\\/blog\\\/el-nuevo-curso-viene-novedades-tics\\\/\"},\"wordCount\":199,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/jovenesendificultad\\\/blog\\\/el-nuevo-curso-viene-novedades-tics\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/utrera.salesianos.edu\\\/jovenesendificultad\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2018\\\/10\\\/20181009_175915.jpg\",\"articleSection\":[\"Portada\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/utrera.salesianos.edu\\\/jovenesendificultad\\\/blog\\\/el-nuevo-curso-viene-novedades-tics\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/jovenesendificultad\\\/blog\\\/el-nuevo-curso-viene-novedades-tics\\\/\",\"url\":\"https:\\\/\\\/utrera.salesianos.edu\\\/jovenesendificultad\\\/blog\\\/el-nuevo-curso-viene-novedades-tics\\\/\",\"name\":\"El nuevo curso viene con novedades TICs - Proyecto Oberti\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/jovenesendificultad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/jovenesendificultad\\\/blog\\\/el-nuevo-curso-viene-novedades-tics\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/jovenesendificultad\\\/blog\\\/el-nuevo-curso-viene-novedades-tics\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/utrera.salesianos.edu\\\/jovenesendificultad\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2018\\\/10\\\/20181009_175915.jpg\",\"datePublished\":\"2018-10-10T11:54:34+00:00\",\"dateModified\":\"2018-12-17T11:10:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/jovenesendificultad\\\/#\\\/schema\\\/person\\\/43f51a01b2adf8fbe0c47356fb20a543\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/jovenesendificultad\\\/blog\\\/el-nuevo-curso-viene-novedades-tics\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/utrera.salesianos.edu\\\/jovenesendificultad\\\/blog\\\/el-nuevo-curso-viene-novedades-tics\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/jovenesendificultad\\\/blog\\\/el-nuevo-curso-viene-novedades-tics\\\/#primaryimage\",\"url\":\"https:\\\/\\\/utrera.salesianos.edu\\\/jovenesendificultad\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2018\\\/10\\\/20181009_175915.jpg\",\"contentUrl\":\"https:\\\/\\\/utrera.salesianos.edu\\\/jovenesendificultad\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2018\\\/10\\\/20181009_175915.jpg\",\"width\":4032,\"height\":2268},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/jovenesendificultad\\\/blog\\\/el-nuevo-curso-viene-novedades-tics\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/utrera.salesianos.edu\\\/jovenesendificultad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El nuevo curso viene con novedades TICs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/jovenesendificultad\\\/#website\",\"url\":\"https:\\\/\\\/utrera.salesianos.edu\\\/jovenesendificultad\\\/\",\"name\":\"Proyecto Oberti\",\"description\":\"Pagina oficial del Proyecto Oberti de la Obra Salesiana en Utrera.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/utrera.salesianos.edu\\\/jovenesendificultad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/utrera.salesianos.edu\\\/jovenesendificultad\\\/#\\\/schema\\\/person\\\/43f51a01b2adf8fbe0c47356fb20a543\",\"name\":\"proyectooberti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fcdf0c4d3cd3ec0cc7b441a68228e463d4659670adf5bc6b3332e93a297f5e44?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fcdf0c4d3cd3ec0cc7b441a68228e463d4659670adf5bc6b3332e93a297f5e44?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fcdf0c4d3cd3ec0cc7b441a68228e463d4659670adf5bc6b3332e93a297f5e44?s=96&d=mm&r=g\",\"caption\":\"proyectooberti\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El nuevo curso viene con novedades TICs - Proyecto Oberti","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/blog\/el-nuevo-curso-viene-novedades-tics\/","og_locale":"es_ES","og_type":"article","og_title":"El nuevo curso viene con novedades TICs - Proyecto Oberti","og_description":"Desde Oberti no podemos mantenernos al margen de los cambios a nivel econ\u00f3mico, social y tecnol\u00f3gico que se est\u00e1n produciendo en la sociedad actual. Es necesario adaptarse a las caracter\u00edsticas individuales y a las necesidades propias de nuestros destinatarios\/as, entre ellas el uso de las TIC en la educaci\u00f3n. De este modo podemos aportar mayor [&hellip;]","og_url":"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/blog\/el-nuevo-curso-viene-novedades-tics\/","og_site_name":"Proyecto Oberti","article_published_time":"2018-10-10T11:54:34+00:00","article_modified_time":"2018-12-17T11:10:13+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/wp-content\/uploads\/sites\/5\/2018\/10\/20181009_175915-1024x576.jpg","type":"image\/jpeg"}],"author":"proyectooberti","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"proyectooberti","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/blog\/el-nuevo-curso-viene-novedades-tics\/#article","isPartOf":{"@id":"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/blog\/el-nuevo-curso-viene-novedades-tics\/"},"author":{"name":"proyectooberti","@id":"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/#\/schema\/person\/43f51a01b2adf8fbe0c47356fb20a543"},"headline":"El nuevo curso viene con novedades TICs","datePublished":"2018-10-10T11:54:34+00:00","dateModified":"2018-12-17T11:10:13+00:00","mainEntityOfPage":{"@id":"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/blog\/el-nuevo-curso-viene-novedades-tics\/"},"wordCount":199,"commentCount":0,"image":{"@id":"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/blog\/el-nuevo-curso-viene-novedades-tics\/#primaryimage"},"thumbnailUrl":"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/wp-content\/uploads\/sites\/5\/2018\/10\/20181009_175915.jpg","articleSection":["Portada"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/utrera.salesianos.edu\/jovenesendificultad\/blog\/el-nuevo-curso-viene-novedades-tics\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/blog\/el-nuevo-curso-viene-novedades-tics\/","url":"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/blog\/el-nuevo-curso-viene-novedades-tics\/","name":"El nuevo curso viene con novedades TICs - Proyecto Oberti","isPartOf":{"@id":"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/blog\/el-nuevo-curso-viene-novedades-tics\/#primaryimage"},"image":{"@id":"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/blog\/el-nuevo-curso-viene-novedades-tics\/#primaryimage"},"thumbnailUrl":"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/wp-content\/uploads\/sites\/5\/2018\/10\/20181009_175915.jpg","datePublished":"2018-10-10T11:54:34+00:00","dateModified":"2018-12-17T11:10:13+00:00","author":{"@id":"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/#\/schema\/person\/43f51a01b2adf8fbe0c47356fb20a543"},"breadcrumb":{"@id":"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/blog\/el-nuevo-curso-viene-novedades-tics\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/utrera.salesianos.edu\/jovenesendificultad\/blog\/el-nuevo-curso-viene-novedades-tics\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/blog\/el-nuevo-curso-viene-novedades-tics\/#primaryimage","url":"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/wp-content\/uploads\/sites\/5\/2018\/10\/20181009_175915.jpg","contentUrl":"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/wp-content\/uploads\/sites\/5\/2018\/10\/20181009_175915.jpg","width":4032,"height":2268},{"@type":"BreadcrumbList","@id":"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/blog\/el-nuevo-curso-viene-novedades-tics\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/"},{"@type":"ListItem","position":2,"name":"El nuevo curso viene con novedades TICs"}]},{"@type":"WebSite","@id":"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/#website","url":"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/","name":"Proyecto Oberti","description":"Pagina oficial del Proyecto Oberti de la Obra Salesiana en Utrera.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/#\/schema\/person\/43f51a01b2adf8fbe0c47356fb20a543","name":"proyectooberti","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fcdf0c4d3cd3ec0cc7b441a68228e463d4659670adf5bc6b3332e93a297f5e44?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fcdf0c4d3cd3ec0cc7b441a68228e463d4659670adf5bc6b3332e93a297f5e44?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fcdf0c4d3cd3ec0cc7b441a68228e463d4659670adf5bc6b3332e93a297f5e44?s=96&d=mm&r=g","caption":"proyectooberti"}}]}},"_links":{"self":[{"href":"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/wp-json\/wp\/v2\/posts\/9894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/wp-json\/wp\/v2\/comments?post=9894"}],"version-history":[{"count":7,"href":"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/wp-json\/wp\/v2\/posts\/9894\/revisions"}],"predecessor-version":[{"id":9925,"href":"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/wp-json\/wp\/v2\/posts\/9894\/revisions\/9925"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/wp-json\/wp\/v2\/media\/9926"}],"wp:attachment":[{"href":"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/wp-json\/wp\/v2\/media?parent=9894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/wp-json\/wp\/v2\/categories?post=9894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/utrera.salesianos.edu\/jovenesendificultad\/wp-json\/wp\/v2\/tags?post=9894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}